

{"id":2875,"date":"2021-03-04T12:44:20","date_gmt":"2021-03-04T11:44:20","guid":{"rendered":"https:\/\/www.fiorentini.com\/soluzioni\/front-end-engineering-design\/"},"modified":"2024-04-27T12:00:37","modified_gmt":"2024-04-27T10:00:37","slug":"progettazione-ingegneristica","status":"publish","type":"post","link":"https:\/\/www.fiorentini.com\/it\/soluzioni\/servizi\/servizi-di-ingegnerizzazione\/progettazione-ingegneristica\/","title":{"rendered":"Progettazione ingegneristica"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Framework di progettazione ingegneristica, il <strong>Front End Engineering Design<\/strong> (FEED) \u00e8 un utilizzato per analizzare in modo dettagliato i costi di un progetto. L&#8217;obiettivo principale di questo approccio \u00e8 analizzare i requisiti del progetto, fissare una base di progettazione, congelare il design e coinvolgere i principali subfornitori. Alla fine di questa esecuzione il FEED restituisce un riassunto dettagliato dei costi che permette ad appaltatori e fornitori di emettere un&#8217;offerta fissa.<br>I team multidisciplinari di Pietro Fiorentini gestiscono il FEED prendendo in considerazione qualsiasi aspetto che riguardi il progetto. Gli obiettivi principali includono la definizione dell&#8217;ingegneria civile, meccanica e di processo, l&#8217;esecuzione di HAZOP e SIL preliminari, la preparazione della lista delle attrezzature principali e il data sheet degli elementi critici, lo sviluppo di modelli 2D e 3D e, infine, la strategia di automazione.<br>Scopo principale del FEED \u00e8 fornire un quadro chiaro di tutti i vincoli del progetto, dagli aspetti tecnici alla sicurezza, comprese le questioni ambientali e, di conseguenza, valutare in modo appronfondito i costi di capitale e funzionamento.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Framework di progettazione ingegneristica, il Front End Engineering Design (FEED) \u00e8 un utilizzato per analizzare in modo dettagliato i costi di un progetto. L&#8217;obiettivo principale di questo approccio \u00e8 analizzare i requisiti del progetto, fissare una base di progettazione, congelare il design e coinvolgere i principali subfornitori. Alla fine di questa esecuzione il FEED restituisce [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":8178,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"template-single-system.php","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[346,377,189,303,347,378,385,390,578,343,582,379,389,391,238,554,386,392,387,388],"tags":[],"class_list":["post-2875","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-trasporto-del-gas-ad-alta-pressione","category-unita-galleggianti","category-soluzioni","category-servizi-di-ingegnerizzazione","category-distribuzione-del-gas-a-media-pressione","category-trattamento-del-gas-it","category-stazioni-di-compressione","category-biremi","category-applicazioni-produzione-di-gas-naturale-e-petrolio","category-applicazioni","category-estrazione-di-gas-naturale","category-stoccaggio-del-petrolio","category-trasporto-gnl-via-mare","category-centrali-elettriche","category-servizi","category-reti-del-gas","category-liquefazione-del-gas","category-industria-pesante","category-stoccaggio-del-gas","category-stazioni-di-primo-salto"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Progettazione ingegneristica dei sistemi | Pietro Fiorentini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fiorentini.com\/it\/soluzioni\/servizi\/servizi-di-ingegnerizzazione\/progettazione-ingegneristica\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Progettazione ingegneristica dei sistemi | Pietro Fiorentini\" \/>\n<meta property=\"og:description\" content=\"Framework di progettazione ingegneristica, il Front End Engineering Design (FEED) \u00e8 un utilizzato per analizzare in modo dettagliato i costi di un progetto. L&#8217;obiettivo principale di questo approccio \u00e8 analizzare i requisiti del progetto, fissare una base di progettazione, congelare il design e coinvolgere i principali subfornitori. Alla fine di questa esecuzione il FEED restituisce [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fiorentini.com\/it\/soluzioni\/servizi\/servizi-di-ingegnerizzazione\/progettazione-ingegneristica\/\" \/>\n<meta property=\"og:site_name\" content=\"Pietro Fiorentini\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-04T11:44:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-27T10:00:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fiorentini.com\/wp-content\/uploads\/2021\/03\/02_feed.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"930\" \/>\n\t<meta property=\"og:image:height\" content=\"930\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Digital Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Digital Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fiorentini.com\\\/it\\\/soluzioni\\\/servizi\\\/servizi-di-ingegnerizzazione\\\/progettazione-ingegneristica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fiorentini.com\\\/it\\\/soluzioni\\\/servizi\\\/servizi-di-ingegnerizzazione\\\/progettazione-ingegneristica\\\/\"},\"author\":{\"name\":\"Digital Team\",\"@id\":\"https:\\\/\\\/www.fiorentini.com\\\/it\\\/#\\\/schema\\\/person\\\/18327c96e0c0b052773d9b81cd57498a\"},\"headline\":\"Progettazione ingegneristica\",\"datePublished\":\"2021-03-04T11:44:20+00:00\",\"dateModified\":\"2024-04-27T10:00:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fiorentini.com\\\/it\\\/soluzioni\\\/servizi\\\/servizi-di-ingegnerizzazione\\\/progettazione-ingegneristica\\\/\"},\"wordCount\":173,\"publisher\":{\"@id\":\"https:\\\/\\\/www.fiorentini.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fiorentini.com\\\/it\\\/soluzioni\\\/servizi\\\/servizi-di-ingegnerizzazione\\\/progettazione-ingegneristica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fiorentini.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/02_feed.jpeg\",\"articleSection\":[\"Trasporto del gas ad alta pressione\",\"Unit\u00e0 galleggianti\",\"Soluzioni\",\"Servizi di ingegnerizzazione\",\"Distribuzione del gas a media pressione\",\"Trattamento del gas\",\"Stazioni di compressione\",\"BiRemi\",\"Produzione di gas naturale e petrolio\",\"Applicazioni\",\"Estrazione di gas naturale\",\"Stoccaggio del petrolio\",\"Trasporto GNL via mare\",\"Centrali elettriche\",\"Servizi\",\"Reti del gas\",\"Liquefazione del gas\",\"Industria pesante\",\"Stoccaggio del gas\",\"Stazioni di primo salto\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fiorentini.com\\\/it\\\/soluzioni\\\/servizi\\\/servizi-di-ingegnerizzazione\\\/progettazione-ingegneristica\\\/\",\"url\":\"https:\\\/\\\/www.fiorentini.com\\\/it\\\/soluzioni\\\/servizi\\\/servizi-di-ingegnerizzazione\\\/progettazione-ingegneristica\\\/\",\"name\":\"Progettazione ingegneristica dei sistemi | Pietro Fiorentini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fiorentini.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.fiorentini.com\\\/it\\\/soluzioni\\\/servizi\\\/servizi-di-ingegnerizzazione\\\/progettazione-ingegneristica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fiorentini.com\\\/it\\\/soluzioni\\\/servizi\\\/servizi-di-ingegnerizzazione\\\/progettazione-ingegneristica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fiorentini.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/02_feed.jpeg\",\"datePublished\":\"2021-03-04T11:44:20+00:00\",\"dateModified\":\"2024-04-27T10:00:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fiorentini.com\\\/it\\\/soluzioni\\\/servizi\\\/servizi-di-ingegnerizzazione\\\/progettazione-ingegneristica\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fiorentini.com\\\/it\\\/soluzioni\\\/servizi\\\/servizi-di-ingegnerizzazione\\\/progettazione-ingegneristica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.fiorentini.com\\\/it\\\/soluzioni\\\/servizi\\\/servizi-di-ingegnerizzazione\\\/progettazione-ingegneristica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.fiorentini.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/02_feed.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.fiorentini.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/02_feed.jpeg\",\"width\":930,\"height\":930},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fiorentini.com\\\/it\\\/soluzioni\\\/servizi\\\/servizi-di-ingegnerizzazione\\\/progettazione-ingegneristica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.fiorentini.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Progettazione ingegneristica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fiorentini.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.fiorentini.com\\\/it\\\/\",\"name\":\"Pietro Fiorentini\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fiorentini.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fiorentini.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.fiorentini.com\\\/it\\\/#organization\",\"name\":\"Pietro Fiorentini\",\"url\":\"https:\\\/\\\/www.fiorentini.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.fiorentini.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.fiorentini.com\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/www.fiorentini.com\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/logo.svg\",\"width\":227,\"height\":59,\"caption\":\"Pietro Fiorentini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fiorentini.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.fiorentini.com\\\/it\\\/#\\\/schema\\\/person\\\/18327c96e0c0b052773d9b81cd57498a\",\"name\":\"Digital Team\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Progettazione ingegneristica dei sistemi | Pietro Fiorentini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fiorentini.com\/it\/soluzioni\/servizi\/servizi-di-ingegnerizzazione\/progettazione-ingegneristica\/","og_locale":"it_IT","og_type":"article","og_title":"Progettazione ingegneristica dei sistemi | Pietro Fiorentini","og_description":"Framework di progettazione ingegneristica, il Front End Engineering Design (FEED) \u00e8 un utilizzato per analizzare in modo dettagliato i costi di un progetto. L&#8217;obiettivo principale di questo approccio \u00e8 analizzare i requisiti del progetto, fissare una base di progettazione, congelare il design e coinvolgere i principali subfornitori. Alla fine di questa esecuzione il FEED restituisce [&hellip;]","og_url":"https:\/\/www.fiorentini.com\/it\/soluzioni\/servizi\/servizi-di-ingegnerizzazione\/progettazione-ingegneristica\/","og_site_name":"Pietro Fiorentini","article_published_time":"2021-03-04T11:44:20+00:00","article_modified_time":"2024-04-27T10:00:37+00:00","og_image":[{"width":930,"height":930,"url":"https:\/\/www.fiorentini.com\/wp-content\/uploads\/2021\/03\/02_feed.jpeg","type":"image\/jpeg"}],"author":"Digital Team","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Digital Team","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fiorentini.com\/it\/soluzioni\/servizi\/servizi-di-ingegnerizzazione\/progettazione-ingegneristica\/#article","isPartOf":{"@id":"https:\/\/www.fiorentini.com\/it\/soluzioni\/servizi\/servizi-di-ingegnerizzazione\/progettazione-ingegneristica\/"},"author":{"name":"Digital Team","@id":"https:\/\/www.fiorentini.com\/it\/#\/schema\/person\/18327c96e0c0b052773d9b81cd57498a"},"headline":"Progettazione ingegneristica","datePublished":"2021-03-04T11:44:20+00:00","dateModified":"2024-04-27T10:00:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fiorentini.com\/it\/soluzioni\/servizi\/servizi-di-ingegnerizzazione\/progettazione-ingegneristica\/"},"wordCount":173,"publisher":{"@id":"https:\/\/www.fiorentini.com\/it\/#organization"},"image":{"@id":"https:\/\/www.fiorentini.com\/it\/soluzioni\/servizi\/servizi-di-ingegnerizzazione\/progettazione-ingegneristica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fiorentini.com\/wp-content\/uploads\/2021\/03\/02_feed.jpeg","articleSection":["Trasporto del gas ad alta pressione","Unit\u00e0 galleggianti","Soluzioni","Servizi di ingegnerizzazione","Distribuzione del gas a media pressione","Trattamento del gas","Stazioni di compressione","BiRemi","Produzione di gas naturale e petrolio","Applicazioni","Estrazione di gas naturale","Stoccaggio del petrolio","Trasporto GNL via mare","Centrali elettriche","Servizi","Reti del gas","Liquefazione del gas","Industria pesante","Stoccaggio del gas","Stazioni di primo salto"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.fiorentini.com\/it\/soluzioni\/servizi\/servizi-di-ingegnerizzazione\/progettazione-ingegneristica\/","url":"https:\/\/www.fiorentini.com\/it\/soluzioni\/servizi\/servizi-di-ingegnerizzazione\/progettazione-ingegneristica\/","name":"Progettazione ingegneristica dei sistemi | Pietro Fiorentini","isPartOf":{"@id":"https:\/\/www.fiorentini.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fiorentini.com\/it\/soluzioni\/servizi\/servizi-di-ingegnerizzazione\/progettazione-ingegneristica\/#primaryimage"},"image":{"@id":"https:\/\/www.fiorentini.com\/it\/soluzioni\/servizi\/servizi-di-ingegnerizzazione\/progettazione-ingegneristica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fiorentini.com\/wp-content\/uploads\/2021\/03\/02_feed.jpeg","datePublished":"2021-03-04T11:44:20+00:00","dateModified":"2024-04-27T10:00:37+00:00","breadcrumb":{"@id":"https:\/\/www.fiorentini.com\/it\/soluzioni\/servizi\/servizi-di-ingegnerizzazione\/progettazione-ingegneristica\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fiorentini.com\/it\/soluzioni\/servizi\/servizi-di-ingegnerizzazione\/progettazione-ingegneristica\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.fiorentini.com\/it\/soluzioni\/servizi\/servizi-di-ingegnerizzazione\/progettazione-ingegneristica\/#primaryimage","url":"https:\/\/www.fiorentini.com\/wp-content\/uploads\/2021\/03\/02_feed.jpeg","contentUrl":"https:\/\/www.fiorentini.com\/wp-content\/uploads\/2021\/03\/02_feed.jpeg","width":930,"height":930},{"@type":"BreadcrumbList","@id":"https:\/\/www.fiorentini.com\/it\/soluzioni\/servizi\/servizi-di-ingegnerizzazione\/progettazione-ingegneristica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fiorentini.com\/it\/"},{"@type":"ListItem","position":2,"name":"Progettazione ingegneristica"}]},{"@type":"WebSite","@id":"https:\/\/www.fiorentini.com\/it\/#website","url":"https:\/\/www.fiorentini.com\/it\/","name":"Pietro Fiorentini","description":"","publisher":{"@id":"https:\/\/www.fiorentini.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fiorentini.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.fiorentini.com\/it\/#organization","name":"Pietro Fiorentini","url":"https:\/\/www.fiorentini.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.fiorentini.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.fiorentini.com\/wp-content\/uploads\/2020\/11\/logo.svg","contentUrl":"https:\/\/www.fiorentini.com\/wp-content\/uploads\/2020\/11\/logo.svg","width":227,"height":59,"caption":"Pietro Fiorentini"},"image":{"@id":"https:\/\/www.fiorentini.com\/it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.fiorentini.com\/it\/#\/schema\/person\/18327c96e0c0b052773d9b81cd57498a","name":"Digital Team"}]}},"_links":{"self":[{"href":"https:\/\/www.fiorentini.com\/it\/wp-json\/wp\/v2\/posts\/2875","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fiorentini.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fiorentini.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fiorentini.com\/it\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fiorentini.com\/it\/wp-json\/wp\/v2\/comments?post=2875"}],"version-history":[{"count":3,"href":"https:\/\/www.fiorentini.com\/it\/wp-json\/wp\/v2\/posts\/2875\/revisions"}],"predecessor-version":[{"id":19587,"href":"https:\/\/www.fiorentini.com\/it\/wp-json\/wp\/v2\/posts\/2875\/revisions\/19587"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fiorentini.com\/it\/wp-json\/wp\/v2\/media\/8178"}],"wp:attachment":[{"href":"https:\/\/www.fiorentini.com\/it\/wp-json\/wp\/v2\/media?parent=2875"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fiorentini.com\/it\/wp-json\/wp\/v2\/categories?post=2875"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fiorentini.com\/it\/wp-json\/wp\/v2\/tags?post=2875"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}